{"id":123429,"date":"2019-09-01T08:00:23","date_gmt":"2019-09-01T08:00:23","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-etiopia-en-kuala-lumpur-malasia\/"},"modified":"2019-09-01T08:00:23","modified_gmt":"2019-09-01T08:00:23","slug":"consulado-general-de-etiopia-en-kuala-lumpur-malasia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-etiopia-en-kuala-lumpur-malasia\/","title":{"rendered":"Consulado General de Etiop\u00eda en Kuala Lumpur, Malasia"},"content":{"rendered":"<div id=\"trave-836251466\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Etiop\u00eda en Kuala Lumpur, Malasia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nNo.2 Jalan Kasipillay Off Jalan Ipoh<br \/>\n51200 Kuala Lumpur<br \/>\nMalasia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+60) 3-2381 1170<br \/>\n<strong>Fax:<\/strong> (+60) 3-2381 1175 \/ 6<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2805294241\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Etiop\u00eda en Kuala Lumpur, Malasia Direcci\u00f3n: No.2 Jalan Kasipillay Off Jalan Ipoh 51200 Kuala Lumpur Malasia Embajador: Tel\u00e9fono: (+60) 3-2381 1170 Fax: (+60) 3-2381 1175 \/ 6 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14650,14133,13335,13290],"tags":[12988],"class_list":["post-123429","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-malasia","category-consulado-general-etiope","category-etiopia","category-malasia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/123429"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=123429"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/123429\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=123429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=123429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=123429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}