{"id":123026,"date":"2019-09-01T07:55:32","date_gmt":"2019-09-01T07:55:32","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-sudan-en-kufra-libia\/"},"modified":"2019-09-01T07:55:32","modified_gmt":"2019-09-01T07:55:32","slug":"consulado-general-de-sudan-en-kufra-libia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-sudan-en-kufra-libia\/","title":{"rendered":"Consulado General de Sud\u00e1n en Kufra, Libia"},"content":{"rendered":"<div id=\"trave-2375728245\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Sud\u00e1n en Kufra, Libia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nKufra<br \/>\nLibia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Essam Abdel-Rahman, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+218) 64 750 3010 \/ 1<br \/>\n<strong>Fax:<\/strong> (+218) 64 750 2342<br \/>\n<strong>Email:<\/strong> sudfra@msn.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-4125383356\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Sud\u00e1n en Kufra, Libia Direcci\u00f3n: Kufra Libia Embajador: Essam Abdel-Rahman, C\u00f3nsul General Tel\u00e9fono: (+218) 64 750 3010 \/ 1 Fax: (+218) 64 750 2342 Email: sudfra@msn.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14142,14620,13257,6591],"tags":[12988],"class_list":["post-123026","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-sudan","category-consulado-general-en-libia","category-libia","category-sudan","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/123026"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=123026"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/123026\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=123026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=123026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=123026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}