{"id":122500,"date":"2019-09-01T07:49:14","date_gmt":"2019-09-01T07:49:14","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-micronesia-en-seul-corea-del-sur-republica-de\/"},"modified":"2019-09-01T07:49:14","modified_gmt":"2019-09-01T07:49:14","slug":"consulado-de-micronesia-en-seul-corea-del-sur-republica-de","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-micronesia-en-seul-corea-del-sur-republica-de\/","title":{"rendered":"Consulado de Micronesia en Se\u00fal, Corea del Sur, Rep\u00fablica de"},"content":{"rendered":"<div id=\"trave-2416923967\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Micronesia en Se\u00fal, Corea del Sur, Rep\u00fablica de<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRoom 605 Ace Twin Tower<br \/>\n212-1 Guro-dong Guro-gu<br \/>\nSe\u00fal<br \/>\nCorea (Rep\u00fablica)<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Myoung-jin Shin, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+82) 2 2109-6930<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-931461580\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Micronesia en Se\u00fal, Corea del Sur, Rep\u00fablica de Direcci\u00f3n: Room 605 Ace Twin Tower 212-1 Guro-dong Guro-gu Se\u00fal Corea (Rep\u00fablica) Embajador: Mr Myoung-jin Shin, C\u00f3nsul Honorario Tel\u00e9fono: (+82) 2 2109-6930 Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14446,14577,13151,6002],"tags":[12978],"class_list":["post-122500","post","type-post","status-publish","format-standard","hentry","category-consulados-de-micronesia","category-consulados-en-corea-del-sur-republica-de","category-corea-del-sur-republica-de","category-micronesia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/122500"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=122500"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/122500\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=122500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=122500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=122500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}