{"id":122167,"date":"2019-09-01T07:45:17","date_gmt":"2019-09-01T07:45:17","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-la-republica-dominicana-en-almaty-kazajstan\/"},"modified":"2019-09-01T07:45:17","modified_gmt":"2019-09-01T07:45:17","slug":"consulado-de-la-republica-dominicana-en-almaty-kazajstan","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-la-republica-dominicana-en-almaty-kazajstan\/","title":{"rendered":"Consulado de la Rep\u00fablica Dominicana en Almaty, Kazajst\u00e1n"},"content":{"rendered":"<div id=\"trave-461050932\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado dominicano en Almaty, Kazajst\u00e1n<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n34 Karasaibat Street<br \/>\n95 Pushkin Street<br \/>\n050010 Almaty<br \/>\nKazajst\u00e1n<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Anuarbek Argingazin, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+7) 701-725 5557<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> hconsulkazak.dr@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2627920177\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado dominicano en Almaty, Kazajst\u00e1n Direcci\u00f3n: 34 Karasaibat Street 95 Pushkin Street 050010 Almaty Kazajst\u00e1n Embajador: Anuarbek Argingazin, C\u00f3nsul Honorario Tel\u00e9fono: (+7) 701-725 5557 Fax: Email: hconsulkazak.dr@gmail.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13482,14556,13139,13481],"tags":[12978],"class_list":["post-122167","post","type-post","status-publish","format-standard","hentry","category-consulados-dominicanos","category-consulados-en-kazajstan","category-kazajstan","category-republica-dominicana","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/122167"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=122167"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/122167\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=122167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=122167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=122167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}