{"id":122150,"date":"2019-09-01T07:45:09","date_gmt":"2019-09-01T07:45:09","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-kirguistan-en-almaty-kazajstan\/"},"modified":"2019-09-01T07:45:09","modified_gmt":"2019-09-01T07:45:09","slug":"consulado-general-de-kirguistan-en-almaty-kazajstan","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-kirguistan-en-almaty-kazajstan\/","title":{"rendered":"Consulado General de Kirguist\u00e1n en Almaty, Kazajst\u00e1n"},"content":{"rendered":"<div id=\"trave-1058199719\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Kirguist\u00e1n en Almaty, Kazajst\u00e1n<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nAlmaty<br \/>\nKazajst\u00e1n<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Alymkulov Aliyasbek Tolbashievich, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+7) (7272) 64-22-11<br \/>\n<strong>Fax:<\/strong> (+7) (7272) 64-22-11<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1447428767\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Kirguist\u00e1n en Almaty, Kazajst\u00e1n Direcci\u00f3n: Almaty Kazajst\u00e1n Embajador: Alymkulov Aliyasbek Tolbashievich, C\u00f3nsul General Tel\u00e9fono: (+7) (7272) 64-22-11 Fax: (+7) (7272) 64-22-11 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14124,14559,13139,13155],"tags":[12988],"class_list":["post-122150","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-kirguistan","category-consulado-general-en-kazajstan","category-kazajstan","category-kirguistan","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/122150"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=122150"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/122150\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=122150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=122150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=122150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}