{"id":122056,"date":"2019-09-01T07:43:54","date_gmt":"2019-09-01T07:43:54","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-uruguay-en-aman-jordania\/"},"modified":"2019-09-01T07:43:54","modified_gmt":"2019-09-01T07:43:54","slug":"consulado-de-uruguay-en-aman-jordania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-uruguay-en-aman-jordania\/","title":{"rendered":"Consulado de Uruguay en Am\u00e1n, Jordania"},"content":{"rendered":"<div id=\"trave-642436438\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado uruguayo en Amman, Jordania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nIntersecci\u00f3n de la Meca y la calle Al-Kindi<br \/>\nKaradsheh Plaza 2, cuarto piso, oficina 43<br \/>\nAmman<br \/>\nJordan<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Omar Anton Naber, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+962) 6-551 0080<br \/>\n<strong>Fax:<\/strong> (+962) 6-551 0080<br \/>\n<strong>Email:<\/strong> uruguay.jo@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2049935096\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado uruguayo en Amman, Jordania Direcci\u00f3n: Intersecci\u00f3n de la Meca y la calle Al-Kindi Karadsheh Plaza 2, cuarto piso, oficina 43 Amman Jordan Embajador: Mr Omar Anton Naber, C\u00f3nsul Honorario Tel\u00e9fono: (+962) 6-551 0080 Fax: (+962) 6-551 0080 Email: uruguay.jo@gmail.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14549,13587,5736,6840],"tags":[12978],"class_list":["post-122056","post","type-post","status-publish","format-standard","hentry","category-consulados-en-jordania","category-consulados-uruguayos","category-jordan","category-uruguay","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/122056"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=122056"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/122056\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=122056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=122056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=122056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}