{"id":122001,"date":"2019-09-01T07:43:13","date_gmt":"2019-09-01T07:43:13","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-seychelles-en-amman-jordania\/"},"modified":"2019-09-01T07:43:13","modified_gmt":"2019-09-01T07:43:13","slug":"consulado-de-seychelles-en-amman-jordania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-seychelles-en-amman-jordania\/","title":{"rendered":"Consulado de Seychelles en Amm\u00e1n, Jordania"},"content":{"rendered":"<div id=\"trave-2530987373\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Seychelles en Amman, Jordania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nPO Box 830226<br \/>\nAmman 11183<br \/>\nJordan<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Izzat Dajani, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+962) (6) 59 38 033<br \/>\n<strong>Fax:<\/strong> (+962) (6) 59 38 022<br \/>\n<strong>Email:<\/strong> dajaniizzat@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 30.30 a 13.30<\/p>\n<div id=\"trave-4025734669\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Seychelles en Amman, Jordania Direcci\u00f3n: PO Box 830226 Amman 11183 Jordan Embajador: Mr Izzat Dajani, C\u00f3nsul Honorario Tel\u00e9fono: (+962) (6) 59 38 033 Fax: (+962) (6) 59 38 022 Email: dajaniizzat@gmail.com Sitio web: Horas de oficina: 30.30 a 13.30<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13876,14549,5736,6461],"tags":[12978],"class_list":["post-122001","post","type-post","status-publish","format-standard","hentry","category-consulados-de-seychelles","category-consulados-en-jordania","category-jordan","category-seychelles","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/122001"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=122001"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/122001\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=122001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=122001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=122001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}