{"id":121980,"date":"2019-09-01T07:43:05","date_gmt":"2019-09-01T07:43:05","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-laos-en-kioto-japon\/"},"modified":"2019-09-01T07:43:05","modified_gmt":"2019-09-01T07:43:05","slug":"consulado-de-laos-en-kioto-japon","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-laos-en-kioto-japon\/","title":{"rendered":"Consulado de Laos en Kioto, Jap\u00f3n"},"content":{"rendered":"<div id=\"trave-20527393\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Laos en Kioto, Jap\u00f3n<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nOhno Building<br \/>\n18 Mibutsujimachi, Nakagyo<br \/>\nKyoto, Kyoto 604-8822<br \/>\nJap\u00f3n<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Yoshihiro Ohno, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+81) 75-801-6291<br \/>\n<strong>Fax:<\/strong> (+81) 75-802-4516<br \/>\n<strong>Email:<\/strong> lao.jpn@gmail.com<br \/>\n<strong>Sitio web:<\/strong> lao-kyoto.com<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1088470497\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Laos en Kioto, Jap\u00f3n Direcci\u00f3n: Ohno Building 18 Mibutsujimachi, Nakagyo Kyoto, Kyoto 604-8822 Jap\u00f3n Embajador: Yoshihiro Ohno, C\u00f3nsul Honorario Tel\u00e9fono: (+81) 75-801-6291 Fax: (+81) 75-802-4516 Email: lao.jpn@gmail.com Sitio web: lao-kyoto.com Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13760,14545,10869,5817],"tags":[12978],"class_list":["post-121980","post","type-post","status-publish","format-standard","hentry","category-consulados-de-laos","category-consulados-en-japon","category-japon","category-laos","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121980"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121980"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121980\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}