{"id":121879,"date":"2019-09-01T07:42:19","date_gmt":"2019-09-01T07:42:19","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-costa-de-marfil-en-tokio-japon\/"},"modified":"2019-09-01T07:42:19","modified_gmt":"2019-09-01T07:42:19","slug":"embajada-de-costa-de-marfil-en-tokio-japon","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-costa-de-marfil-en-tokio-japon\/","title":{"rendered":"Embajada de Costa de Marfil en Tokio, Jap\u00f3n"},"content":{"rendered":"<div id=\"trave-1939574560\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Costa de Marfil en Tokio, Jap\u00f3n<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n2-19-12, Uehara, Shibuya-ku<br \/>\nTokio 151-0064<br \/>\nJap\u00f3n<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. J\u00e9r\u00e9me Kl&#8217;h Weya, Embajador<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+81) 3-5454-1401 \/ 2 \/ 3<br \/>\n<strong>Fax:<\/strong> (+81) 3-5454-1405<br \/>\n<strong>Email:<\/strong> ambacijn@yahoo.fr<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00-16.00<\/p>\n<div id=\"trave-3479557406\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Costa de Marfil en Tokio, Jap\u00f3n Direcci\u00f3n: 2-19-12, Uehara, Shibuya-ku Tokio 151-0064 Jap\u00f3n Embajador: Sr. J\u00e9r\u00e9me Kl&#8217;h Weya, Embajador Tel\u00e9fono: (+81) 3-5454-1401 \/ 2 \/ 3 Fax: (+81) 3-5454-1405 Email: ambacijn@yahoo.fr Sitio web: Horas de oficina: 09.00-16.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13340,13341,14544,10869],"tags":[12975],"class_list":["post-121879","post","type-post","status-publish","format-standard","hentry","category-costa-de-marfil","category-embajadas-de-costa-de-marfil","category-embajadas-en-japon","category-japon","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121879"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121879"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121879\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}