{"id":121782,"date":"2019-09-01T07:41:38","date_gmt":"2019-09-01T07:41:38","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-francia-en-hiroshima-japon\/"},"modified":"2019-09-01T07:41:38","modified_gmt":"2019-09-01T07:41:38","slug":"consulado-de-francia-en-hiroshima-japon","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-francia-en-hiroshima-japon\/","title":{"rendered":"Consulado de Francia en Hiroshima, Jap\u00f3n"},"content":{"rendered":"<div id=\"trave-3677357003\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado franc\u00e9s en Hiroshima, Jap\u00f3n<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nHiroshima TV Plaza 6F<br \/>\n6-30, Nakamachi, Naka-ku<br \/>\nHiroshima 730-0037<br \/>\nJap\u00f3n<br \/>\n<strong><br \/>\nEmbajador:<\/strong> K\u00f4sei Mochizuki, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+81) 82-245-8570<br \/>\n<strong>Fax:<\/strong> (+81) 82-245-8570<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2873999768\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado franc\u00e9s en Hiroshima, Jap\u00f3n Direcci\u00f3n: Hiroshima TV Plaza 6F 6-30, Nakamachi, Naka-ku Hiroshima 730-0037 Jap\u00f3n Embajador: K\u00f4sei Mochizuki, C\u00f3nsul Honorario Tel\u00e9fono: (+81) 82-245-8570 Fax: (+81) 82-245-8570 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14545,13518,13000,10869],"tags":[12978],"class_list":["post-121782","post","type-post","status-publish","format-standard","hentry","category-consulados-en-japon","category-consulados-franceses","category-francia","category-japon","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121782"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121782"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121782\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}