{"id":121595,"date":"2019-09-01T07:39:59","date_gmt":"2019-09-01T07:39:59","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-tailandia-en-kingston-jamaica\/"},"modified":"2019-09-01T07:39:59","modified_gmt":"2019-09-01T07:39:59","slug":"consulado-general-de-tailandia-en-kingston-jamaica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-tailandia-en-kingston-jamaica\/","title":{"rendered":"Consulado General de Tailandia en Kingston, Jamaica"},"content":{"rendered":"<div id=\"trave-3467693393\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Tailandia en Kingston, Jamaica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nReal Consulado General de Tailandia en Kingston, Jamaica<br \/>\n2 Valentine Drive<br \/>\nKingston 19<br \/>\nJamaica<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mrs Thalia Lyn, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1 876) 925-8181<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> pa@thaiconsulatejm.org<br \/>\nthalialyn@thaiconsulatejm.org<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 9:00 am &#8211; 4:00 pm<\/p>\n<div id=\"trave-4251653455\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Tailandia en Kingston, Jamaica Direcci\u00f3n: Real Consulado General de Tailandia en Kingston, Jamaica 2 Valentine Drive Kingston 19 Jamaica Embajador: Mrs Thalia Lyn, C\u00f3nsul General Honorario Tel\u00e9fono: (+1 876) 925-8181 Fax: Email: pa@thaiconsulatejm.org thalialyn@thaiconsulatejm.org Sitio web: Horas de oficina: 9:00 am &#8211; 4:00 pm<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13709,14541,5713,13188],"tags":[12988],"class_list":["post-121595","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-tailandia","category-consulado-general-en-jamaica","category-jamaica","category-tailandia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121595"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121595"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121595\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}