{"id":121584,"date":"2019-09-01T07:39:59","date_gmt":"2019-09-01T07:39:59","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-peru-en-montego-bay-jamaica\/"},"modified":"2019-09-01T07:39:59","modified_gmt":"2019-09-01T07:39:59","slug":"consulado-de-peru-en-montego-bay-jamaica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-peru-en-montego-bay-jamaica\/","title":{"rendered":"Consulado de Per\u00fa en Montego Bay, Jamaica"},"content":{"rendered":"<div id=\"trave-4290571819\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado peruano en Montego Bay, Jamaica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nMontego Bay<br \/>\nJamaica<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Susana P. Pereyra de Byles, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08:00 &#8211; 16:00<\/p>\n<div id=\"trave-606555902\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado peruano en Montego Bay, Jamaica Direcci\u00f3n: Montego Bay Jamaica Embajador: Susana P. Pereyra de Byles, C\u00f3nsul Honorario Tel\u00e9fono: Fax: Email: Sitio web: Horas de oficina: 08:00 &#8211; 16:00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14540,13563,5713,6261],"tags":[12978],"class_list":["post-121584","post","type-post","status-publish","format-standard","hentry","category-consulados-en-jamaica","category-consulados-peruanos","category-jamaica","category-peru","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121584"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121584"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121584\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}