{"id":121568,"date":"2019-09-01T07:39:51","date_gmt":"2019-09-01T07:39:51","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-barbados-en-kingston-jamaica\/"},"modified":"2019-09-01T07:39:51","modified_gmt":"2019-09-01T07:39:51","slug":"consulado-de-barbados-en-kingston-jamaica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-barbados-en-kingston-jamaica\/","title":{"rendered":"Consulado de Barbados en Kingston, Jamaica"},"content":{"rendered":"<div id=\"trave-2052443163\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Barbados en Kingston, Jamaica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nPO Box 518<br \/>\nKingston 8<br \/>\nJamaica<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Winston Bayley, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1 876) 977-2855<br \/>\n(+1 876) 977-1710<br \/>\n<strong>Fax:<\/strong> (+1 876) 977-2855<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2788257922\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Barbados en Kingston, Jamaica Direcci\u00f3n: PO Box 518 Kingston 8 Jamaica Embajador: Mr Winston Bayley, C\u00f3nsul Honorario Tel\u00e9fono: (+1 876) 977-2855 (+1 876) 977-1710 Fax: (+1 876) 977-2855 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4906,13533,14540,5713],"tags":[12978],"class_list":["post-121568","post","type-post","status-publish","format-standard","hentry","category-barbados","category-consulados-de-barbados","category-consulados-en-jamaica","category-jamaica","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121568"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121568"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121568\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}