{"id":121468,"date":"2019-09-01T07:38:50","date_gmt":"2019-09-01T07:38:50","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-canada-en-milan-italia\/"},"modified":"2019-09-01T07:38:50","modified_gmt":"2019-09-01T07:38:50","slug":"consulado-de-canada-en-milan-italia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-canada-en-milan-italia\/","title":{"rendered":"Consulado de Canad\u00e1 en Mil\u00e1n, Italia"},"content":{"rendered":"<div id=\"trave-4211604471\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado canadiense en Mil\u00e1n, Italia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n3 Piazza Cavour, sexto piso<br \/>\n20121 Mil\u00e1n<br \/>\nItalia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Ezio Maria Simonelli, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+39) 02 6269 4238<br \/>\n<strong>Fax:<\/strong> (+39) 02 2901 3600<br \/>\n<strong>Email:<\/strong> consul.canada.milan@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 13.00<\/p>\n<div id=\"trave-97053151\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado canadiense en Mil\u00e1n, Italia Direcci\u00f3n: 3 Piazza Cavour, sexto piso 20121 Mil\u00e1n Italia Embajador: Ezio Maria Simonelli, C\u00f3nsul Honorario Tel\u00e9fono: (+39) 02 6269 4238 Fax: (+39) 02 2901 3600 Email: consul.canada.milan@gmail.com Sitio web: Horas de oficina: 09.00 a 13.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5085,13171,14529,13062],"tags":[12978],"class_list":["post-121468","post","type-post","status-publish","format-standard","hentry","category-canada","category-consulados-canadienses","category-consulados-en-italia","category-italia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121468"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121468"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121468\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}