{"id":121450,"date":"2019-09-01T07:38:42","date_gmt":"2019-09-01T07:38:42","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-bangladesh-en-florencia-italia\/"},"modified":"2019-09-01T07:38:42","modified_gmt":"2019-09-01T07:38:42","slug":"consulado-general-de-bangladesh-en-florencia-italia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-bangladesh-en-florencia-italia\/","title":{"rendered":"Consulado General de Bangladesh en Florencia, Italia"},"content":{"rendered":"<div id=\"trave-3069299547\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Bangladesh en Florencia, Italia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nVia Pellicceria, 6<br \/>\n50123 Firenze<br \/>\nItalia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Giorgia Granata, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+39) 05 521 7500<br \/>\n<strong>Fax:<\/strong> (+39) 05 521 7500<br \/>\n<strong>Email:<\/strong> giorgiagranata@hotmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-4204260543\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Bangladesh en Florencia, Italia Direcci\u00f3n: Via Pellicceria, 6 50123 Firenze Italia Embajador: Giorgia Granata, C\u00f3nsul General Honorario Tel\u00e9fono: (+39) 05 521 7500 Fax: (+39) 05 521 7500 Email: giorgiagranata@hotmail.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4892,13703,14530,13062],"tags":[12988],"class_list":["post-121450","post","type-post","status-publish","format-standard","hentry","category-bangladesh","category-consulado-general-de-bangladesh","category-consulado-general-en-italia","category-italia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121450"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121450"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121450\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}