{"id":121420,"date":"2019-09-01T07:38:25","date_gmt":"2019-09-01T07:38:25","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-samoa-en-roma-italia\/"},"modified":"2019-09-01T07:38:25","modified_gmt":"2019-09-01T07:38:25","slug":"consulado-general-de-samoa-en-roma-italia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-samoa-en-roma-italia\/","title":{"rendered":"Consulado General de Samoa en Roma, Italia"},"content":{"rendered":"<div id=\"trave-2374826079\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Samoa en Roma, Italia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nVia Bocca di Leone, 25<br \/>\nScala B, piano 4, introducci\u00f3n 8<br \/>\n00187 Roma<br \/>\nItalia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Giovanni Caffarelli, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+39) 06 699 223 51<br \/>\n<strong>Fax:<\/strong> (+39) 06 699 223 51<br \/>\n<strong>Email:<\/strong> samoaroma@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-652894450\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Samoa en Roma, Italia Direcci\u00f3n: Via Bocca di Leone, 25 Scala B, piano 4, introducci\u00f3n 8 00187 Roma Italia Embajador: Giovanni Caffarelli, C\u00f3nsul Honorario Tel\u00e9fono: (+39) 06 699 223 51 Fax: (+39) 06 699 223 51 Email: samoaroma@gmail.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13472,14530,13062,6406],"tags":[12988],"class_list":["post-121420","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-samoa","category-consulado-general-en-italia","category-italia","category-samoa","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121420"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121420"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121420\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}