{"id":121407,"date":"2019-09-01T07:38:25","date_gmt":"2019-09-01T07:38:25","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-ucrania-en-milan-italia\/"},"modified":"2019-09-01T07:38:25","modified_gmt":"2019-09-01T07:38:25","slug":"consulado-general-de-ucrania-en-milan-italia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-ucrania-en-milan-italia\/","title":{"rendered":"Consulado General de Ucrania en Mil\u00e1n, Italia"},"content":{"rendered":"<div id=\"trave-1667682066\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Ucrania en Mil\u00e1n, Italia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n20156 Mil\u00e1n<br \/>\nItalia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Goriainov Roman, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+39) (02) 869 84 863<br \/>\n(+39) (02) 869 98 814<br \/>\n<strong>Fax:<\/strong> (+39) (02) 869 84 863<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-431032515\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Ucrania en Mil\u00e1n, Italia Direcci\u00f3n: 20156 Mil\u00e1n Italia Embajador: Mr Goriainov Roman, C\u00f3nsul General Tel\u00e9fono: (+39) (02) 869 84 863 (+39) (02) 869 98 814 Fax: (+39) (02) 869 84 863 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13866,14530,13062,13254],"tags":[12988],"class_list":["post-121407","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-ucrania","category-consulado-general-en-italia","category-italia","category-ucrania","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121407"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121407"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121407\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}