{"id":121065,"date":"2019-09-01T07:35:37","date_gmt":"2019-09-01T07:35:37","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-suecia-en-milan-italia\/"},"modified":"2019-09-01T07:35:37","modified_gmt":"2019-09-01T07:35:37","slug":"consulado-general-de-suecia-en-milan-italia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-suecia-en-milan-italia\/","title":{"rendered":"Consulado General de Suecia en Mil\u00e1n, Italia"},"content":{"rendered":"<div id=\"trave-1056780077\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado sueco en Mil\u00e1n, Italia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n20121 Mil\u00e1n MI<br \/>\nItalia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Marco Frazzica, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+39) 02 859 102 11<br \/>\n<strong>Fax:<\/strong> (+39) 02 859 102 11<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 10.00-12.00<\/p>\n<div id=\"trave-336388015\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado sueco en Mil\u00e1n, Italia Direcci\u00f3n: 20121 Mil\u00e1n MI Italia Embajador: Mr Marco Frazzica, C\u00f3nsul General Honorario Tel\u00e9fono: (+39) 02 859 102 11 Fax: (+39) 02 859 102 11 Email: Sitio web: Horas de oficina: 10.00-12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14530,13696,13062,13073],"tags":[12988],"class_list":["post-121065","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-italia","category-consulado-general-sueco","category-italia","category-suecia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121065"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121065"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121065\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}