{"id":121004,"date":"2019-09-01T07:35:07","date_gmt":"2019-09-01T07:35:07","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-belice-en-milan-italia\/"},"modified":"2019-09-01T07:35:07","modified_gmt":"2019-09-01T07:35:07","slug":"consulado-de-belice-en-milan-italia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-belice-en-milan-italia\/","title":{"rendered":"Consulado de Belice en Mil\u00e1n, Italia"},"content":{"rendered":"<div id=\"trave-1366789868\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Belice en Mil\u00e1n, Italia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n20015 San Lorenzo di Parabiago<br \/>\nItalia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mrs Wendy Theresa John Charles d&#8217;Angeri, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+39) 03 3149 3850<br \/>\n<strong>Fax:<\/strong> (+39) 03 3149 3850<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-676704617\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Belice en Mil\u00e1n, Italia Direcci\u00f3n: 20015 San Lorenzo di Parabiago Italia Embajador: Mrs Wendy Theresa John Charles d&#8217;Angeri, C\u00f3nsul Honorario Tel\u00e9fono: (+39) 03 3149 3850 Fax: (+39) 03 3149 3850 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13686,13687,14529,13062],"tags":[12978],"class_list":["post-121004","post","type-post","status-publish","format-standard","hentry","category-belice","category-consulados-de-belice","category-consulados-en-italia","category-italia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121004"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=121004"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/121004\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=121004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=121004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=121004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}