{"id":120933,"date":"2019-09-01T07:34:31","date_gmt":"2019-09-01T07:34:31","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-las-bahamas-en-milan-italia\/"},"modified":"2019-09-01T07:34:31","modified_gmt":"2019-09-01T07:34:31","slug":"consulado-de-las-bahamas-en-milan-italia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-las-bahamas-en-milan-italia\/","title":{"rendered":"Consulado de las Bahamas en Mil\u00e1n, Italia"},"content":{"rendered":"<div id=\"trave-2972845521\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de las Bahamas en Mil\u00e1n, Italia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nVia Mascheroni, 1<br \/>\n20123 Mil\u00e1n<br \/>\nItalia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sra. Michelangela Vismara, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+39) 024 819 4390<br \/>\n(+39) 335 803 914<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> consolatobahamas@vertexic.com<br \/>\nitalymilanhcmofa@bahamas.gov.bs<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-4149158431\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de las Bahamas en Mil\u00e1n, Italia Direcci\u00f3n: Via Mascheroni, 1 20123 Mil\u00e1n Italia Embajador: Sra. Michelangela Vismara, C\u00f3nsul Honorario Tel\u00e9fono: (+39) 024 819 4390 (+39) 335 803 914 Fax: Email: consolatobahamas@vertexic.com italymilanhcmofa@bahamas.gov.bs Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4875,13552,14529,13062],"tags":[12978],"class_list":["post-120933","post","type-post","status-publish","format-standard","hentry","category-bahamas","category-consulados-de-las-bahamas","category-consulados-en-italia","category-italia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120933"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=120933"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120933\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=120933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=120933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=120933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}