{"id":120878,"date":"2019-09-01T07:34:07","date_gmt":"2019-09-01T07:34:07","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-la-republica-checa-en-napoles-italia\/"},"modified":"2019-09-01T07:34:07","modified_gmt":"2019-09-01T07:34:07","slug":"consulado-de-la-republica-checa-en-napoles-italia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-la-republica-checa-en-napoles-italia\/","title":{"rendered":"Consulado de la Rep\u00fablica checa en N\u00e1poles, Italia"},"content":{"rendered":"<div id=\"trave-3666042630\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado checo en N\u00e1poles, Italia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nCorso Umberto I., 275<br \/>\n80138 N\u00e1poles<br \/>\nItalia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Dr. Angelo Ruoppolo, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+39) 081 268784<br \/>\n<strong>Fax:<\/strong> (+39) 081 267336<br \/>\n<strong>Email:<\/strong> naples@honorary.mzv.cz<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 10.00-12.00<\/p>\n<div id=\"trave-3190376877\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado checo en N\u00e1poles, Italia Direcci\u00f3n: Corso Umberto I., 275 80138 N\u00e1poles Italia Embajador: Dr. Angelo Ruoppolo, C\u00f3nsul Honorario Tel\u00e9fono: (+39) 081 268784 Fax: (+39) 081 267336 Email: naples@honorary.mzv.cz Sitio web: Horas de oficina: 10.00-12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13478,14529,13062,13146],"tags":[12978],"class_list":["post-120878","post","type-post","status-publish","format-standard","hentry","category-consulados-checos","category-consulados-en-italia","category-italia","category-republica-checa","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120878"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=120878"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120878\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=120878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=120878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=120878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}