{"id":120792,"date":"2019-09-01T07:33:22","date_gmt":"2019-09-01T07:33:22","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-monaco-en-milan-italia\/"},"modified":"2019-09-01T07:33:22","modified_gmt":"2019-09-01T07:33:22","slug":"consulado-de-monaco-en-milan-italia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-monaco-en-milan-italia\/","title":{"rendered":"Consulado de M\u00f3naco en Mil\u00e1n, Italia"},"content":{"rendered":"<div id=\"trave-2449850071\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado Monegasco en Mil\u00e1n, Italia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nVia Aurelio Saffi, 34<br \/>\n20123 Mil\u00e1n<br \/>\nItalia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Jacopo de Mojana di Cologna, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+39) 024.80.12.038<br \/>\n<strong>Fax:<\/strong> (+39) 024.85.19.101<br \/>\n<strong>Email:<\/strong> consulatdemonaco.milan@demojana.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1236342673\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado Monegasco en Mil\u00e1n, Italia Direcci\u00f3n: Via Aurelio Saffi, 34 20123 Mil\u00e1n Italia Embajador: Mr Jacopo de Mojana di Cologna, C\u00f3nsul Honorario Tel\u00e9fono: (+39) 024.80.12.038 Fax: (+39) 024.85.19.101 Email: consulatdemonaco.milan@demojana.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14529,13541,13062,6017],"tags":[12978],"class_list":["post-120792","post","type-post","status-publish","format-standard","hentry","category-consulados-en-italia","category-consulados-monegascos","category-italia","category-monaco","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120792"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=120792"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120792\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=120792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=120792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=120792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}