{"id":120692,"date":"2019-09-01T07:32:11","date_gmt":"2019-09-01T07:32:11","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-del-reino-unido-en-jerusalen-israel\/"},"modified":"2019-09-01T07:32:11","modified_gmt":"2019-09-01T07:32:11","slug":"consulado-general-del-reino-unido-en-jerusalen-israel","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-del-reino-unido-en-jerusalen-israel\/","title":{"rendered":"Consulado General del Reino Unido en Jerusal\u00e9n, Israel"},"content":{"rendered":"<div id=\"trave-1731979557\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado Brit\u00e1nico en Jerusal\u00e9n, Israel<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n15 Nashashibi Street<br \/>\nSheikh Jarrah Quarter<br \/>\nP. O. Box 19690<br \/>\nJerusal\u00e9n Este 97200<br \/>\nIsrael<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Dr. Alastair McPhail, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+972) 2 541 4100<br \/>\n<strong>Fax:<\/strong> (+972) 2 532 2368<br \/>\n<strong>Email:<\/strong> britain.jerusalem@fco.gov.uk<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2157266424\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado Brit\u00e1nico en Jerusal\u00e9n, Israel Direcci\u00f3n: 15 Nashashibi Street Sheikh Jarrah Quarter P. O. Box 19690 Jerusal\u00e9n Este 97200 Israel Embajador: Dr. Alastair McPhail, C\u00f3nsul General Tel\u00e9fono: (+972) 2 541 4100 Fax: (+972) 2 532 2368 Email: britain.jerusalem@fco.gov.uk Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13702,14519,5685,13069],"tags":[12988],"class_list":["post-120692","post","type-post","status-publish","format-standard","hentry","category-consulado-general-britanico","category-consulado-general-en-israel","category-israel","category-reino-unido","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120692"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=120692"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120692\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=120692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=120692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=120692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}