{"id":120441,"date":"2019-09-01T07:29:30","date_gmt":"2019-09-01T07:29:30","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-turquia-en-mosul-iraq\/"},"modified":"2019-09-01T07:29:30","modified_gmt":"2019-09-01T07:29:30","slug":"consulado-general-de-turquia-en-mosul-iraq","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-turquia-en-mosul-iraq\/","title":{"rendered":"Consulado General de Turqu\u00eda en Mosul, Iraq"},"content":{"rendered":"<div id=\"trave-2082355604\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado turco en Mosul, Iraq<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nDur Al-Dhubat Caddesi<br \/>\njunto a la mezquita Al-Shekban<br \/>\nNo: 5\/2 Al-Tayaran Mahallesi<br \/>\nMosul, Ninawa,<br \/>\nIraq<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+964) (60) 780 591<br \/>\n<strong>Fax:<\/strong> (+964) (60) 780 591<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1785585526\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado turco en Mosul, Iraq Direcci\u00f3n: Dur Al-Dhubat Caddesi junto a la mezquita Al-Shekban No: 5\/2 Al-Tayaran Mahallesi Mosul, Ninawa, Iraq Embajador: Tel\u00e9fono: (+964) (60) 780 591 Fax: (+964) (60) 780 591 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14500,13162,10840,13161],"tags":[12988],"class_list":["post-120441","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-iraq","category-consulado-general-turco","category-irak","category-pavo","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120441"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=120441"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120441\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=120441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=120441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=120441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}