{"id":120197,"date":"2019-09-01T07:26:40","date_gmt":"2019-09-01T07:26:40","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-japon-en-surabaya-indonesia\/"},"modified":"2019-09-01T07:26:40","modified_gmt":"2019-09-01T07:26:40","slug":"consulado-general-de-japon-en-surabaya-indonesia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-japon-en-surabaya-indonesia\/","title":{"rendered":"Consulado General de Jap\u00f3n en Surabaya, Indonesia"},"content":{"rendered":"<div id=\"trave-908325630\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado japon\u00e9s en Surabaya, Indonesia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nSurabaya 60281, Java Oriental<br \/>\nIndonesia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+62) (31) 503-0037<br \/>\n<strong>Fax:<\/strong> (+62) (31) 503-0037<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3237786871\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado japon\u00e9s en Surabaya, Indonesia Direcci\u00f3n: Surabaya 60281, Java Oriental Indonesia Embajador: Tel\u00e9fono: (+62) (31) 503-0037 Fax: (+62) (31) 503-0037 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14485,13561,5637,10869],"tags":[12988],"class_list":["post-120197","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-indonesia","category-consulado-general-japones","category-indonesia","category-japon","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120197"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=120197"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/120197\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=120197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=120197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=120197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}