{"id":119926,"date":"2019-09-01T07:23:46","date_gmt":"2019-09-01T07:23:46","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-comoras-en-nueva-delhi-india\/"},"modified":"2019-09-01T07:23:46","modified_gmt":"2019-09-01T07:23:46","slug":"consulado-general-de-comoras-en-nueva-delhi-india","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-comoras-en-nueva-delhi-india\/","title":{"rendered":"Consulado General de Comoras en Nueva Delhi, India"},"content":{"rendered":"<div id=\"trave-6283956\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Comoran en Nueva Delhi, India<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n13\/14, Old Rajinder Nagar<br \/>\nNueva Delhi 110 060<br \/>\nIndia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Kanahiya Lal Ganju, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+91) 11 2874 1319<br \/>\n(+91) 11 2874 1328<br \/>\n<strong>Fax:<\/strong> (+91) 11 2874 1326<br \/>\n(+91) 11 2582 3110<br \/>\n<strong>Email:<\/strong> klganju_comoros@hotmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 10.00-14.00<\/p>\n<div id=\"trave-2118272173\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Comoran en Nueva Delhi, India Direcci\u00f3n: 13\/14, Old Rajinder Nagar Nueva Delhi 110 060 India Embajador: Mr Kanahiya Lal Ganju, C\u00f3nsul Honorario Tel\u00e9fono: (+91) 11 2874 1319 (+91) 11 2874 1328 Fax: (+91) 11 2874 1326 (+91) 11 2582 3110 Email: klganju_comoros@hotmail.com Sitio web: Horas de oficina: 10.00-14.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13908,14475,14458,5621],"tags":[12988],"class_list":["post-119926","post","type-post","status-publish","format-standard","hentry","category-comoras","category-consulado-general-de-comoran","category-consulado-general-en-india","category-india","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119926"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=119926"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119926\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=119926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=119926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=119926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}