{"id":119778,"date":"2019-09-01T07:22:20","date_gmt":"2019-09-01T07:22:20","guid":{"rendered":"https:\/\/travelqa.com\/alta-comision-de-pakistan-en-nueva-delhi-india\/"},"modified":"2019-09-01T07:22:20","modified_gmt":"2019-09-01T07:22:20","slug":"alta-comision-de-pakistan-en-nueva-delhi-india","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/alta-comision-de-pakistan-en-nueva-delhi-india\/","title":{"rendered":"Alta Comisi\u00f3n de Pakist\u00e1n en Nueva Delhi, India"},"content":{"rendered":"<div id=\"trave-1642863739\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Alta Comisi\u00f3n de Pakist\u00e1n en Nueva Delhi, India<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nChanakyapuri<br \/>\nNueva Delhi 110021<br \/>\nIndia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+91) (11) 2611 0601 \/ 2 \/ 5<br \/>\n<strong>Fax:<\/strong> (+91) (11) 2687 2339<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 10.00-16.00<\/p>\n<div id=\"trave-293962867\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Alta Comisi\u00f3n de Pakist\u00e1n en Nueva Delhi, India Direcci\u00f3n: Chanakyapuri Nueva Delhi 110021 India Embajador: Tel\u00e9fono: (+91) (11) 2611 0601 \/ 2 \/ 5 Fax: (+91) (11) 2687 2339 Email: Sitio web: Horas de oficina: 10.00-16.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13695,14460,5621,6205],"tags":[13640],"class_list":["post-119778","post","type-post","status-publish","format-standard","hentry","category-altas-comisiones-de-pakistan","category-altas-comisiones-en-india","category-india","category-pakistan","tag-alta-comision"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119778"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=119778"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119778\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=119778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=119778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=119778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}