{"id":119773,"date":"2019-09-01T07:22:20","date_gmt":"2019-09-01T07:22:20","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-filipinas-en-mumbai-india\/"},"modified":"2019-09-01T07:22:20","modified_gmt":"2019-09-01T07:22:20","slug":"consulado-general-de-filipinas-en-mumbai-india","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-filipinas-en-mumbai-india\/","title":{"rendered":"Consulado General de Filipinas en Mumbai, India"},"content":{"rendered":"<div id=\"trave-571555165\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Filipinas en Mumbai, India<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nChurchgate Reclamation<br \/>\nMumbai 400020<br \/>\nIndia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+91) 22-2202 4792<br \/>\n<strong>Fax:<\/strong> (+91) 22-2281-4103<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Lunes a viernes: 10.00 a 12.00<\/p>\n<div id=\"trave-3367663207\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Filipinas en Mumbai, India Direcci\u00f3n: Churchgate Reclamation Mumbai 400020 India Embajador: Tel\u00e9fono: (+91) 22-2202 4792 Fax: (+91) 22-2281-4103 Email: Sitio web: Horas de oficina: Lunes a viernes: 10.00 a 12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13494,14458,13195,5621],"tags":[12988],"class_list":["post-119773","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-filipinas","category-consulado-general-en-india","category-filipinas","category-india","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119773"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=119773"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119773\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=119773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=119773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=119773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}