{"id":119767,"date":"2019-09-01T07:22:20","date_gmt":"2019-09-01T07:22:20","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-grecia-en-mumbai-india\/"},"modified":"2019-09-01T07:22:20","modified_gmt":"2019-09-01T07:22:20","slug":"consulado-general-de-grecia-en-mumbai-india","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-grecia-en-mumbai-india\/","title":{"rendered":"Consulado General de Grecia en Mumbai, India"},"content":{"rendered":"<div id=\"trave-3898617233\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado griego en Mumbai, India<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nBaharestan<br \/>\n30 \/ A, Juhu Tara Road<br \/>\nJuhu<br \/>\nMumbai 400 049<br \/>\nIndia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Jeroo Mango, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+91) 22 2660 7852<br \/>\n<strong>Fax:<\/strong> (+91) 22 2660 7431<br \/>\n<strong>Email:<\/strong> jertony@yahoo.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 10.00-16.00<\/p>\n<div id=\"trave-1347337683\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado griego en Mumbai, India Direcci\u00f3n: Baharestan 30 \/ A, Juhu Tara Road Juhu Mumbai 400 049 India Embajador: Mr Jeroo Mango, C\u00f3nsul General Honorario Tel\u00e9fono: (+91) 22 2660 7852 Fax: (+91) 22 2660 7431 Email: jertony@yahoo.com Sitio web: Horas de oficina: 10.00-16.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14458,13240,13238,5621],"tags":[12988],"class_list":["post-119767","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-india","category-consulado-general-griego","category-grecia","category-india","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119767"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=119767"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119767\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=119767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=119767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=119767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}