{"id":119694,"date":"2019-09-01T07:21:29","date_gmt":"2019-09-01T07:21:29","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-la-republica-checa-en-bangalore-india\/"},"modified":"2019-09-01T07:21:29","modified_gmt":"2019-09-01T07:21:29","slug":"consulado-de-la-republica-checa-en-bangalore-india","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-la-republica-checa-en-bangalore-india\/","title":{"rendered":"Consulado de la Rep\u00fablica checa en Bangalore, India"},"content":{"rendered":"<div id=\"trave-3382266839\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado checo en Bangalore, India<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nJalahalli<br \/>\nBangalore, Estado de Karnataka<br \/>\nIndia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+91) 984 504 8998<br \/>\n(+91) 734 936 8900<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 10.00 &#8211; 14.00<\/p>\n<div id=\"trave-3108446363\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado checo en Bangalore, India Direcci\u00f3n: Jalahalli Bangalore, Estado de Karnataka India Embajador: Tel\u00e9fono: (+91) 984 504 8998 (+91) 734 936 8900 Fax: Email: Sitio web: Horas de oficina: 10.00 &#8211; 14.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13478,14459,5621,13146],"tags":[12978],"class_list":["post-119694","post","type-post","status-publish","format-standard","hentry","category-consulados-checos","category-consulados-en-india","category-india","category-republica-checa","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119694"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=119694"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119694\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=119694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=119694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=119694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}