{"id":119241,"date":"2019-09-01T07:12:04","date_gmt":"2019-09-01T07:12:04","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-suecia-en-tegucigalpa-honduras\/"},"modified":"2019-09-01T07:12:04","modified_gmt":"2019-09-01T07:12:04","slug":"consulado-general-de-suecia-en-tegucigalpa-honduras","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-suecia-en-tegucigalpa-honduras\/","title":{"rendered":"Consulado General de Suecia en Tegucigalpa, Honduras"},"content":{"rendered":"<div id=\"trave-360796218\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado sueco en Tegucigalpa, Honduras<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nFuerzas Armadas<br \/>\nCostado Oeste Plaza Millennium<br \/>\nComayaguela<br \/>\nHonduras<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Juliette Handal de Castillo, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1849839977\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado sueco en Tegucigalpa, Honduras Direcci\u00f3n: Fuerzas Armadas Costado Oeste Plaza Millennium Comayaguela Honduras Embajador: Juliette Handal de Castillo, C\u00f3nsul General Honorario Tel\u00e9fono: Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14434,13696,5584,13073],"tags":[12988],"class_list":["post-119241","post","type-post","status-publish","format-standard","hentry","category-consulado-general-en-honduras","category-consulado-general-sueco","category-honduras","category-suecia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119241"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=119241"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/119241\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=119241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=119241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=119241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}