{"id":118906,"date":"2019-09-01T07:07:26","date_gmt":"2019-09-01T07:07:26","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-belice-en-ciudad-de-guatemala-guatemala\/"},"modified":"2019-09-01T07:07:26","modified_gmt":"2019-09-01T07:07:26","slug":"embajada-de-belice-en-ciudad-de-guatemala-guatemala","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-belice-en-ciudad-de-guatemala-guatemala\/","title":{"rendered":"Embajada de Belice en Ciudad de Guatemala, Guatemala"},"content":{"rendered":"<div id=\"trave-563107484\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Belice en Ciudad de Guatemala, Guatemala<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nEuroplaza Torre II, Officina 1502<br \/>\nCiudad de<br \/>\nGuatemala Guatemala<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. Alexis Roberto Rosado, Embajador<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+502) 2207-4001 \/ 2207-4020<br \/>\n(+502) 2367-3883<br \/>\n<strong>Fax:<\/strong> (+502) 2207-4001 \/ 2207-4020<br \/>\n(+502) 2367-3884<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09:00 &#8211; 13:00 \/ 14:00 &#8211; 17:00<\/p>\n<div id=\"trave-1357927577\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Belice en Ciudad de Guatemala, Guatemala Direcci\u00f3n: Europlaza Torre II, Officina 1502 Ciudad de Guatemala Guatemala Embajador: Sr. Alexis Roberto Rosado, Embajador Tel\u00e9fono: (+502) 2207-4001 \/ 2207-4020 (+502) 2367-3883 Fax: (+502) 2207-4001 \/ 2207-4020 (+502) 2367-3884 Email: Sitio web: Horas de oficina: 09:00 &#8211; 13:00 \/ 14:00 &#8211; 17:00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13686,13886,14407,5533],"tags":[12975],"class_list":["post-118906","post","type-post","status-publish","format-standard","hentry","category-belice","category-embajadas-de-belice","category-embajadas-en-guatemala","category-guatemala","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118906"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118906"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118906\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}