{"id":118888,"date":"2019-09-01T07:07:16","date_gmt":"2019-09-01T07:07:16","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-austria-en-ciudad-de-guatemala-guatemala\/"},"modified":"2019-09-01T07:07:16","modified_gmt":"2019-09-01T07:07:16","slug":"consulado-general-de-austria-en-ciudad-de-guatemala-guatemala","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-austria-en-ciudad-de-guatemala-guatemala\/","title":{"rendered":"Consulado General de Austria en Ciudad de Guatemala, Guatemala"},"content":{"rendered":"<div id=\"trave-1053773620\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Austria en Ciudad de Guatemala, Guatemala<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nEdificio Multim\u00e9dico Blvd.Vista Hermosa 25-19<br \/>\n\u00c1rea 15 Nivel 12, Oficina 1218<br \/>\nGuatemala Ciudad<br \/>\nGuatemala<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Manuel Caceres, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+502) 2332 1506<br \/>\n<strong>Fax:<\/strong> (+502) 2334 83394<br \/>\n<strong>Email:<\/strong> consuladodeaustria.gua@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Lunes: 14.30 &#8211; 17.30<br \/>\nmi\u00e9rcoles: 10.00 &#8211; 13.00<\/p>\n<div id=\"trave-1675974153\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Austria en Ciudad de Guatemala, Guatemala Direcci\u00f3n: Edificio Multim\u00e9dico Blvd.Vista Hermosa 25-19 \u00c1rea 15 Nivel 12, Oficina 1218 Guatemala Ciudad Guatemala Embajador: Mr Manuel Caceres, C\u00f3nsul General Honorario Tel\u00e9fono: (+502) 2332 1506 Fax: (+502) 2334 83394 Email: consuladodeaustria.gua@gmail.com Sitio web: Horas de oficina: Lunes: 14.30 &#8211; 17.30 mi\u00e9rcoles: 10.00 &#8211; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4857,13646,14406,5533],"tags":[12988],"class_list":["post-118888","post","type-post","status-publish","format-standard","hentry","category-austria","category-consulado-general-de-austria","category-consulado-general-en-guatemala","category-guatemala","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118888"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118888"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118888\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}