{"id":118811,"date":"2019-09-01T07:05:13","date_gmt":"2019-09-01T07:05:13","guid":{"rendered":"https:\/\/travelqa.com\/agencia-consular-de-francia-en-alexandroupoli-grecia\/"},"modified":"2019-09-01T07:05:13","modified_gmt":"2019-09-01T07:05:13","slug":"agencia-consular-de-francia-en-alexandroupoli-grecia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/agencia-consular-de-francia-en-alexandroupoli-grecia\/","title":{"rendered":"Agencia Consular de Francia en Alexandroupoli, Grecia"},"content":{"rendered":"<div id=\"trave-2925073890\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Agencia Consular Francesa en Alexandroupoli, Grecia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n681 00 Alexandroupoli<br \/>\nGrecia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Marina Doulamis, Agente Consular<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+30) 25510.23.272<br \/>\n<strong>Fax:<\/strong> (+30) 25510.23.272<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1749758609\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Agencia Consular Francesa en Alexandroupoli, Grecia Direcci\u00f3n: 681 00 Alexandroupoli Grecia Embajador: Marina Doulamis, Agente Consular Tel\u00e9fono: (+30) 25510.23.272 Fax: (+30) 25510.23.272 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14383,13566,13000,13238],"tags":[13532],"class_list":["post-118811","post","type-post","status-publish","format-standard","hentry","category-agencias-consulares-en-grecia","category-agencias-consulares-francesas","category-francia","category-grecia","tag-agencia-consular"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118811"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118811"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118811\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}