{"id":118784,"date":"2019-09-01T07:05:03","date_gmt":"2019-09-01T07:05:03","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-surinam-en-atenas-grecia\/"},"modified":"2019-09-01T07:05:03","modified_gmt":"2019-09-01T07:05:03","slug":"consulado-de-surinam-en-atenas-grecia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-surinam-en-atenas-grecia\/","title":{"rendered":"Consulado de Surinam en Atenas, Grecia"},"content":{"rendered":"<div id=\"trave-1298218433\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado de Suriname en Atenas, Grecia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nN. Economou &#038; Co.Ltd.Comerciantes y representantes<br \/>\n3, rue Kolokotroni<br \/>\n105 62 Atenas<br \/>\nGrecia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Nicolas D. Economou, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+30) 210.32.21.421<br \/>\n(+30) 210.32.23.427<br \/>\n<strong>Fax:<\/strong> (+30) 210.32.28.466<br \/>\n<strong>Email:<\/strong> econhc@internet.gr<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1873280580\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado de Suriname en Atenas, Grecia Direcci\u00f3n: N. Economou &#038; Co.Ltd.Comerciantes y representantes 3, rue Kolokotroni 105 62 Atenas Grecia Embajador: Mr Nicolas D. Economou, C\u00f3nsul Honorario Tel\u00e9fono: (+30) 210.32.21.421 (+30) 210.32.23.427 Fax: (+30) 210.32.28.466 Email: econhc@internet.gr Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13821,14379,13238,13820],"tags":[12978],"class_list":["post-118784","post","type-post","status-publish","format-standard","hentry","category-consulados-de-suriname","category-consulados-en-grecia","category-grecia","category-surinam","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118784"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118784"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118784\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}