{"id":118638,"date":"2019-09-01T07:03:26","date_gmt":"2019-09-01T07:03:26","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-irlanda-en-atenas-grecia\/"},"modified":"2019-09-01T07:03:26","modified_gmt":"2019-09-01T07:03:26","slug":"embajada-de-irlanda-en-atenas-grecia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-irlanda-en-atenas-grecia\/","title":{"rendered":"Embajada de Irlanda en Atenas, Grecia"},"content":{"rendered":"<div id=\"trave-779526268\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la embajada de Irlanda en Atenas, Grecia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n7, Leoforos Vasileos Konstantinou<br \/>\n106 74 Atenas<br \/>\nGrecia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. Noel Kilkenny, embajador<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+30) 210-723-2771 &#8211; 2<br \/>\n<strong>Fax:<\/strong> (+30) 210-729 3383<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> www.dfa.ie\/irish-embassy\/greece\/<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1745235415\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la embajada de Irlanda en Atenas, Grecia Direcci\u00f3n: 7, Leoforos Vasileos Konstantinou 106 74 Atenas Grecia Embajador: Sr. Noel Kilkenny, embajador Tel\u00e9fono: (+30) 210-723-2771 &#8211; 2 Fax: (+30) 210-729 3383 Email: Sitio web: www.dfa.ie\/irish-embassy\/greece\/ Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14380,13583,13238,13582],"tags":[12975],"class_list":["post-118638","post","type-post","status-publish","format-standard","hentry","category-embajadas-en-grecia","category-embajadas-irlandesas","category-grecia","category-irlanda","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118638"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118638"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118638\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}