{"id":118622,"date":"2019-09-01T07:03:12","date_gmt":"2019-09-01T07:03:12","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-los-paises-bajos-en-corfu-grecia\/"},"modified":"2019-09-01T07:03:12","modified_gmt":"2019-09-01T07:03:12","slug":"consulado-de-los-paises-bajos-en-corfu-grecia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-los-paises-bajos-en-corfu-grecia\/","title":{"rendered":"Consulado de los Pa\u00edses Bajos en Corf\u00fa, Grecia"},"content":{"rendered":"<div id=\"trave-1623055702\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado holand\u00e9s en Corf\u00fa, Grecia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nDirecci\u00f3n postal: Kapoditriou e Idromenon 2<br \/>\n49100 Corf\u00fa<br \/>\nGrecia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> V. Nicolakis-Mouhas, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+30) 26610-399 00<br \/>\n<strong>Fax:<\/strong> (+30) 26610-399 00<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Lunes, mi\u00e9rcoles, viernes: 10.00 a 12.00<\/p>\n<div id=\"trave-3308970106\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado holand\u00e9s en Corf\u00fa, Grecia Direcci\u00f3n: Direcci\u00f3n postal: Kapoditriou e Idromenon 2 49100 Corf\u00fa Grecia Embajador: V. Nicolakis-Mouhas, C\u00f3nsul Honorario Tel\u00e9fono: (+30) 26610-399 00 Fax: (+30) 26610-399 00 Email: Sitio web: Horas de oficina: Lunes, mi\u00e9rcoles, viernes: 10.00 a 12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13527,14379,13238,13067],"tags":[12978],"class_list":["post-118622","post","type-post","status-publish","format-standard","hentry","category-consulados-de-holanda","category-consulados-en-grecia","category-grecia","category-paises-bajos","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118622"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118622"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118622\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}