{"id":118533,"date":"2019-09-01T07:02:11","date_gmt":"2019-09-01T07:02:11","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-sudafrica-en-atenas-grecia\/"},"modified":"2019-09-01T07:02:11","modified_gmt":"2019-09-01T07:02:11","slug":"embajada-de-sudafrica-en-atenas-grecia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-sudafrica-en-atenas-grecia\/","title":{"rendered":"Embajada de Sud\u00e1frica en Atenas, Grecia"},"content":{"rendered":"<div id=\"trave-856786511\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la embajada de Sud\u00e1frica en Atenas, Grecia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nMarousi<br \/>\n15125 Atenas<br \/>\nP. O. Box<br \/>\n61152 151-10 Atenas<br \/>\nGrecia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+30) 210 617 8020<br \/>\n<strong>Fax:<\/strong> (+30) 210 610 6636<br \/>\n(+30) 210 610 6640<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2978142014\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la embajada de Sud\u00e1frica en Atenas, Grecia Direcci\u00f3n: Marousi 15125 Atenas P. O. Box 61152 151-10 Atenas Grecia Embajador: Tel\u00e9fono: (+30) 210 617 8020 Fax: (+30) 210 610 6636 (+30) 210 610 6640 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14380,13326,13238,13251],"tags":[12975],"class_list":["post-118533","post","type-post","status-publish","format-standard","hentry","category-embajadas-en-grecia","category-embajadas-sudafricanas","category-grecia","category-sudafrica","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118533"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118533"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118533\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}