{"id":118461,"date":"2019-09-01T07:01:05","date_gmt":"2019-09-01T07:01:05","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-ben-en-accra-ghana\/"},"modified":"2019-09-01T07:01:05","modified_gmt":"2019-09-01T07:01:05","slug":"embajada-de-ben-en-accra-ghana","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-ben-en-accra-ghana\/","title":{"rendered":"Embajada de Ben en Accra, Ghana"},"content":{"rendered":"<div id=\"trave-4221781708\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la embajada de Benin en Accra, Ghana<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nNo.25 Airport West Road<br \/>\nCerca del aeropuerto West Hotel y cerca de la oficina central de Fedex<br \/>\nP.O.Box CT 758, Acuartelamientos<br \/>\nAccra<br \/>\nGhana<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Martine-Francoise Dossa, Embajadora<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+233) 302 774 860<br \/>\n<strong>Fax:<\/strong> (+233) 302 774 889<br \/>\n<strong>Email:<\/strong> ambab.accra@yahoo.fr<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.00 a 15.00<\/p>\n<div id=\"trave-3526984812\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la embajada de Benin en Accra, Ghana Direcci\u00f3n: No.25 Airport West Road Cerca del aeropuerto West Hotel y cerca de la oficina central de Fedex P.O.Box CT 758, Acuartelamientos Accra Ghana Embajador: Martine-Francoise Dossa, Embajadora Tel\u00e9fono: (+233) 302 774 860 Fax: (+233) 302 774 889 Email: ambab.accra@yahoo.fr Sitio web: Horas de oficina: 08.00 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4948,13346,14370,5482],"tags":[12975],"class_list":["post-118461","post","type-post","status-publish","format-standard","hentry","category-benin","category-embajadas-de-benin","category-embajadas-en-ghana","category-ghana","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118461"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118461"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118461\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}