{"id":118263,"date":"2019-09-01T06:58:46","date_gmt":"2019-09-01T06:58:46","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-noruega-en-munich-alemania\/"},"modified":"2019-09-01T06:58:46","modified_gmt":"2019-09-01T06:58:46","slug":"consulado-de-noruega-en-munich-alemania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-noruega-en-munich-alemania\/","title":{"rendered":"Consulado de Noruega en Munich, Alemania"},"content":{"rendered":"<div id=\"trave-1536933994\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado de Noruega en Munich, Alemania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nMaffeistrasse, 3<br \/>\n80333 M\u00fcnchen<br \/>\nAlemania<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Max J. Aschenbrenner, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+49) 89 22 41 70<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> office@norwegischer-honorarkonsul-muenchen.de<br \/>\n<strong>Sitio web:<\/strong> www.norwegisches-konsulat-muenchen.de<\/p>\n<p><strong>Horas de oficina:<\/strong> Lunes a jueves: 14.00 a 17.30<br \/>\nviernes: 09.00 a 12.00<br \/>\nSolo con cita previa<\/p>\n<div id=\"trave-3151107306\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado de Noruega en Munich, Alemania Direcci\u00f3n: Maffeistrasse, 3 80333 M\u00fcnchen Alemania Embajador: Mr Max J. Aschenbrenner, C\u00f3nsul Honorario Tel\u00e9fono: (+49) 89 22 41 70 Fax: Email: office@norwegischer-honorarkonsul-muenchen.de Sitio web: www.norwegisches-konsulat-muenchen.de Horas de oficina: Lunes a jueves: 14.00 a 17.30 viernes: 09.00 a 12.00 Solo con cita previa<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,13529,14348,13153],"tags":[12978],"class_list":["post-118263","post","type-post","status-publish","format-standard","hentry","category-alemania","category-consulados-de-noruega","category-consulados-en-alemania","category-noruega","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118263"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118263"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118263\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}