{"id":118196,"date":"2019-09-01T06:58:12","date_gmt":"2019-09-01T06:58:12","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-gambia-en-berlin-alemania\/"},"modified":"2019-09-01T06:58:12","modified_gmt":"2019-09-01T06:58:12","slug":"consulado-de-gambia-en-berlin-alemania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-gambia-en-berlin-alemania\/","title":{"rendered":"Consulado de Gambia en Berl\u00edn, Alemania"},"content":{"rendered":"<div id=\"trave-2411838169\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado de Gambia en Berl\u00edn, Alemania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nBerl\u00edn 10627<br \/>\nAlemania<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Roman Skoblo, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+49) 30 89 11 401<br \/>\n<strong>Fax:<\/strong> (+49) 30 89 11 401<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Martes y jueves: 10.00 a 12.00<\/p>\n<div id=\"trave-3397210731\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado de Gambia en Berl\u00edn, Alemania Direcci\u00f3n: Berl\u00edn 10627 Alemania Embajador: Roman Skoblo, C\u00f3nsul Honorario Tel\u00e9fono: (+49) 30 89 11 401 Fax: (+49) 30 89 11 401 Email: Sitio web: Horas de oficina: Martes y jueves: 10.00 a 12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,13845,14348,5449],"tags":[12978],"class_list":["post-118196","post","type-post","status-publish","format-standard","hentry","category-alemania","category-consulados-de-gambia","category-consulados-en-alemania","category-gambia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118196"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118196"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118196\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}