{"id":118189,"date":"2019-09-01T06:58:07","date_gmt":"2019-09-01T06:58:07","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-la-republica-checa-en-francfort-del-meno-alemania\/"},"modified":"2019-09-01T06:58:07","modified_gmt":"2019-09-01T06:58:07","slug":"consulado-de-la-republica-checa-en-francfort-del-meno-alemania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-la-republica-checa-en-francfort-del-meno-alemania\/","title":{"rendered":"Consulado de la Rep\u00fablica checa en Fr\u00e1ncfort del Meno, Alemania"},"content":{"rendered":"<div id=\"trave-3970237310\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado checo en Frankfurt am Main, Alemania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nFrankfurt am Main 60322<br \/>\nAlemania<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Dr Robin Leon Fritz, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+49) 69 959 573 01<br \/>\n<strong>Fax:<\/strong> (+49) 69 959 573 01<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Martes y jueves:<br \/>\n10.00 a 13.00 Mi\u00e9rcoles: 10.00 a 13.00, 14.00 a 16.00<br \/>\nLunes 13.00 a 16.00<\/p>\n<div id=\"trave-3990420621\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado checo en Frankfurt am Main, Alemania Direcci\u00f3n: Frankfurt am Main 60322 Alemania Embajador: Dr Robin Leon Fritz, C\u00f3nsul Honorario Tel\u00e9fono: (+49) 69 959 573 01 Fax: (+49) 69 959 573 01 Email: Sitio web: Horas de oficina: Martes y jueves: 10.00 a 13.00 Mi\u00e9rcoles: 10.00 a 13.00, 14.00 a 16.00 Lunes 13.00 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,13478,14348,13146],"tags":[12978],"class_list":["post-118189","post","type-post","status-publish","format-standard","hentry","category-alemania","category-consulados-checos","category-consulados-en-alemania","category-republica-checa","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118189"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118189"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118189\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}