{"id":118151,"date":"2019-09-01T06:57:43","date_gmt":"2019-09-01T06:57:43","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-bangladesh-en-munich-alemania\/"},"modified":"2019-09-01T06:57:43","modified_gmt":"2019-09-01T06:57:43","slug":"consulado-general-de-bangladesh-en-munich-alemania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-bangladesh-en-munich-alemania\/","title":{"rendered":"Consulado General de Bangladesh en M\u00fanich, Alemania"},"content":{"rendered":"<div id=\"trave-1280475533\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Bangladesh en Munich, Alemania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nM\u00fcnchen 80333<br \/>\nAlemania<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Dr. Michael Brauch, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+49) 89 286 401 60<br \/>\n<strong>Fax:<\/strong> (+49) 89 286 401 60<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Lunes a viernes: 09.00 a 12.00<\/p>\n<div id=\"trave-182562158\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Bangladesh en Munich, Alemania Direcci\u00f3n: M\u00fcnchen 80333 Alemania Embajador: Dr. Michael Brauch, C\u00f3nsul General Honorario Tel\u00e9fono: (+49) 89 286 401 60 Fax: (+49) 89 286 401 60 Email: Sitio web: Horas de oficina: Lunes a viernes: 09.00 a 12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,4892,13703,14349],"tags":[12988],"class_list":["post-118151","post","type-post","status-publish","format-standard","hentry","category-alemania","category-bangladesh","category-consulado-general-de-bangladesh","category-consulado-general-en-alemania","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118151"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118151"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118151\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}