{"id":118023,"date":"2019-09-01T06:56:28","date_gmt":"2019-09-01T06:56:28","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-espana-en-dusseldorf-alemania\/"},"modified":"2019-09-01T06:56:28","modified_gmt":"2019-09-01T06:56:28","slug":"consulado-general-de-espana-en-dusseldorf-alemania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-espana-en-dusseldorf-alemania\/","title":{"rendered":"Consulado General de Espa\u00f1a en D\u00fcsseldorf, Alemania"},"content":{"rendered":"<div id=\"trave-423943650\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado espa\u00f1ol en D\u00fcsseldorf, Alemania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nHomberger Strasse 16<br \/>\n40474 D\u00fcsseldorf<br \/>\nAlemania<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mercedes Alonso Frayle, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+49) 211 43 90 80<br \/>\n<strong>Fax:<\/strong> (+49) 211 43 80 31 5<br \/>\n<strong>Email:<\/strong> cog.dusseldorf@mae.es<br \/>\n<strong>Sitio web:<\/strong> www.exteriores.gob.es\/consulados\/dusseldorf<\/p>\n<p><strong>Horas de oficina:<\/strong> Lunes a viernes: 08.00 a 14.00<\/p>\n<div id=\"trave-2784603044\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado espa\u00f1ol en D\u00fcsseldorf, Alemania Direcci\u00f3n: Homberger Strasse 16 40474 D\u00fcsseldorf Alemania Embajador: Mercedes Alonso Frayle, C\u00f3nsul General Tel\u00e9fono: (+49) 211 43 90 80 Fax: (+49) 211 43 80 31 5 Email: cog.dusseldorf@mae.es Sitio web: www.exteriores.gob.es\/consulados\/dusseldorf Horas de oficina: Lunes a viernes: 08.00 a 14.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,14349,13354,13134],"tags":[12988],"class_list":["post-118023","post","type-post","status-publish","format-standard","hentry","category-alemania","category-consulado-general-en-alemania","category-consulado-general-espanol","category-espana","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118023"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=118023"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/118023\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=118023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=118023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=118023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}