{"id":117910,"date":"2019-09-01T06:55:29","date_gmt":"2019-09-01T06:55:29","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-irlanda-en-munich-alemania\/"},"modified":"2019-09-01T06:55:29","modified_gmt":"2019-09-01T06:55:29","slug":"consulado-general-de-irlanda-en-munich-alemania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-irlanda-en-munich-alemania\/","title":{"rendered":"Consulado General de Irlanda en Munich, Alemania"},"content":{"rendered":"<div id=\"trave-3087909324\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Irlanda en Munich, Alemania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nDenninger Strasse 15<br \/>\n81679 Munich<br \/>\nAlemania<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Erich J. Lejeune, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+49) 89 20 80 5990<br \/>\n<strong>Fax:<\/strong> (+49) 89 20 80 5993<br \/>\n<strong>Email:<\/strong> info@irl-consulate.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Lunes a viernes: 09.00 a 12.00<\/p>\n<div id=\"trave-685581796\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Irlanda en Munich, Alemania Direcci\u00f3n: Denninger Strasse 15 81679 Munich Alemania Embajador: Mr Erich J. Lejeune, C\u00f3nsul General Honorario Tel\u00e9fono: (+49) 89 20 80 5990 Fax: (+49) 89 20 80 5993 Email: info@irl-consulate.com Sitio web: Horas de oficina: Lunes a viernes: 09.00 a 12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,14349,13692,13582],"tags":[12988],"class_list":["post-117910","post","type-post","status-publish","format-standard","hentry","category-alemania","category-consulado-general-en-alemania","category-consulado-general-irlandes","category-irlanda","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117910"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=117910"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117910\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=117910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=117910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=117910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}