{"id":117764,"date":"2019-09-01T06:53:57","date_gmt":"2019-09-01T06:53:57","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-india-en-hamburgo-alemania\/"},"modified":"2019-09-01T06:53:57","modified_gmt":"2019-09-01T06:53:57","slug":"consulado-general-de-india-en-hamburgo-alemania","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-india-en-hamburgo-alemania\/","title":{"rendered":"Consulado General de India en Hamburgo, Alemania"},"content":{"rendered":"<div id=\"trave-3009259337\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de India en Hamburgo, Alemania<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n20487 Hamburgo<br \/>\nAlemania<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Madan Lal Raigar, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+49) 40 32 37 57<br \/>\n(+49) 40 33 05 57 \/ 32 47 44<br \/>\n<strong>Fax:<\/strong> (+49) 40 32 37 57<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1639931236\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de India en Hamburgo, Alemania Direcci\u00f3n: 20487 Hamburgo Alemania Embajador: Madan Lal Raigar, C\u00f3nsul General Tel\u00e9fono: (+49) 40 32 37 57 (+49) 40 33 05 57 \/ 32 47 44 Fax: (+49) 40 32 37 57 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,14349,13004,5621],"tags":[12988],"class_list":["post-117764","post","type-post","status-publish","format-standard","hentry","category-alemania","category-consulado-general-en-alemania","category-consulado-general-indio","category-india","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117764"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=117764"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117764\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=117764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=117764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=117764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}