{"id":117556,"date":"2019-09-01T06:51:18","date_gmt":"2019-09-01T06:51:18","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-sudafrica-en-banjul-gambia\/"},"modified":"2019-09-01T06:51:18","modified_gmt":"2019-09-01T06:51:18","slug":"consulado-de-sudafrica-en-banjul-gambia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-sudafrica-en-banjul-gambia\/","title":{"rendered":"Consulado de Sud\u00e1frica en Banjul, Gambia"},"content":{"rendered":"<div id=\"trave-1964065560\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado de Sud\u00e1frica en Banjul, Gambia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nPO Box 4555<br \/>\nBakau<br \/>\nBanjul<br \/>\nGambia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr M. Sulayman Barra Taal, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+220) 4461 955<br \/>\n<strong>Fax:<\/strong> (+220) 4461 955<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3900050542\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado de Sud\u00e1frica en Banjul, Gambia Direcci\u00f3n: PO Box 4555 Bakau Banjul Gambia Embajador: Mr M. Sulayman Barra Taal, C\u00f3nsul Honorario Tel\u00e9fono: (+220) 4461 955 Fax: (+220) 4461 955 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13252,14334,5449,13251],"tags":[12978],"class_list":["post-117556","post","type-post","status-publish","format-standard","hentry","category-consulados-de-sudafrica","category-consulados-en-gambia","category-gambia","category-sudafrica","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117556"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=117556"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117556\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=117556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=117556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=117556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}