{"id":117459,"date":"2019-09-01T06:49:40","date_gmt":"2019-09-01T06:49:40","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-noruega-en-papeete-polinesia-francesa\/"},"modified":"2019-09-01T06:49:40","modified_gmt":"2019-09-01T06:49:40","slug":"consulado-de-noruega-en-papeete-polinesia-francesa","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-noruega-en-papeete-polinesia-francesa\/","title":{"rendered":"Consulado de Noruega en Papeete, Polinesia Francesa"},"content":{"rendered":"<div id=\"trave-1391570820\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado de Noruega en Papeete, Polinesia Francesa<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nBoulevard Pomare<br \/>\nBP 274<br \/>\n98713 Papeete<br \/>\nPolinesia Francesa<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Maeva Siu, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+689) 40 42 89 72<br \/>\n(+689) 87 77 05 43<br \/>\n<strong>Fax:<\/strong> (+689) 40 43 21 84<br \/>\n<strong>Email:<\/strong> maeva@amitahiti.pf<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2316380925\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado de Noruega en Papeete, Polinesia Francesa Direcci\u00f3n: Boulevard Pomare BP 274 98713 Papeete Polinesia Francesa Embajador: Maeva Siu, C\u00f3nsul Honorario Tel\u00e9fono: (+689) 40 42 89 72 (+689) 87 77 05 43 Fax: (+689) 40 43 21 84 Email: maeva@amitahiti.pf Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13529,14325,13153,14324],"tags":[12978],"class_list":["post-117459","post","type-post","status-publish","format-standard","hentry","category-consulados-de-noruega","category-consulados-en-polinesia-francesa","category-noruega","category-polinesia-frances","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117459"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=117459"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117459\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=117459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=117459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=117459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}