{"id":117425,"date":"2019-09-01T06:49:03","date_gmt":"2019-09-01T06:49:03","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-argelia-en-paris-francia-2\/"},"modified":"2019-09-01T06:49:03","modified_gmt":"2019-09-01T06:49:03","slug":"consulado-de-argelia-en-paris-francia-2","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-argelia-en-paris-francia-2\/","title":{"rendered":"Consulado de Argelia en Par\u00eds, Francia"},"content":{"rendered":"<div id=\"trave-3762217851\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del Consulado de Argelia en Par\u00eds, Francia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n63, Avenue Georges Clemenceau<br \/>\nB.P.1411<br \/>\n92000 Nanterre<br \/>\nFrancia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Abdelaziz Doudou, C\u00f3nsul<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+33) 1 47.25.12.71<br \/>\n<strong>Fax:<\/strong> (+33) 1 47.25.09.77<br \/>\n<strong>Email:<\/strong> consulat.algerie.nanterre@orange.fr<br \/>\n<strong>Sitio web:<\/strong> www.consulat-nanterre-algerie.fr<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-336381130\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del Consulado de Argelia en Par\u00eds, Francia Direcci\u00f3n: 63, Avenue Georges Clemenceau B.P.1411 92000 Nanterre Francia Embajador: Mr Abdelaziz Doudou, C\u00f3nsul Tel\u00e9fono: (+33) 1 47.25.12.71 Fax: (+33) 1 47.25.09.77 Email: consulat.algerie.nanterre@orange.fr Sitio web: www.consulat-nanterre-algerie.fr Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13275,14311,14310,13000],"tags":[12978],"class_list":["post-117425","post","type-post","status-publish","format-standard","hentry","category-argelia","category-consulados-de-argelia","category-consulados-en-francia","category-francia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117425"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=117425"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117425\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=117425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=117425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=117425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}