{"id":117307,"date":"2019-09-01T06:47:52","date_gmt":"2019-09-01T06:47:52","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-panama-en-marsella-francia\/"},"modified":"2019-09-01T06:47:52","modified_gmt":"2019-09-01T06:47:52","slug":"consulado-general-de-panama-en-marsella-francia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-panama-en-marsella-francia\/","title":{"rendered":"Consulado General de Panam\u00e1 en Marsella, Francia"},"content":{"rendered":"<div id=\"trave-237524392\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Panam\u00e1 en Marsella, Francia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n11 Quai Des Belges<br \/>\n13001 Marsella<br \/>\nFrancia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Maria Isabel Villegas, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+33) 4 9190 0584<br \/>\n<strong>Fax:<\/strong> (+33) 4 9191 1026<br \/>\n<strong>Email:<\/strong> consulatpanama-marseille@hotmail.com<br \/>\n<strong>Sitio web:<\/strong> www.consulatdepanama-marseille.com<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3404773173\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Panam\u00e1 en Marsella, Francia Direcci\u00f3n: 11 Quai Des Belges 13001 Marsella Francia Embajador: Maria Isabel Villegas, C\u00f3nsul General Tel\u00e9fono: (+33) 4 9190 0584 Fax: (+33) 4 9191 1026 Email: consulatpanama-marseille@hotmail.com Sitio web: www.consulatdepanama-marseille.com Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13740,14309,13000,6231],"tags":[12988],"class_list":["post-117307","post","type-post","status-publish","format-standard","hentry","category-consulado-general-de-panama","category-consulado-general-en-francia","category-francia","category-panama","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117307"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=117307"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/117307\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=117307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=117307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=117307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}